{"id":3303,"date":"2026-03-28T20:33:32","date_gmt":"2026-03-28T12:33:32","guid":{"rendered":"https:\/\/www.transyncai.com\/?post_type=docs&#038;p=3303"},"modified":"2026-05-27T16:27:49","modified_gmt":"2026-05-27T08:27:49","password":"","slug":"how-to-use-voice-playback-in-transync-ai","status":"publish","type":"docs","link":"https:\/\/www.transyncai.com\/pt\/docs\/how-to-use-voice-playback-in-transync-ai\/","title":{"rendered":"Como usar a reprodu\u00e7\u00e3o de voz no Transync AI"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A Reprodu\u00e7\u00e3o de Voz permite que a IA da Transync leia o texto traduzido em voz alta no idioma de destino selecionado. Isso \u00e9 \u00fatil quando voc\u00ea deseja que outras pessoas tamb\u00e9m leiam o texto traduzido. <strong>ouvir<\/strong> A tradu\u00e7\u00e3o, e n\u00e3o apenas a leitura de legendas na tela.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Por exemplo, se a sua reuni\u00e3o for em ingl\u00eas e voc\u00ea quiser reprodu\u00e7\u00e3o em japon\u00eas, voc\u00ea pode ativar a reprodu\u00e7\u00e3o de voz nas configura\u00e7\u00f5es. <strong>en \u2192 ja<\/strong> Selecione a voz que preferir. Voc\u00ea pode ativar a transmiss\u00e3o de voz para o idioma desejado e escolher o tom de voz preferido.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Antes de usar a reprodu\u00e7\u00e3o de voz, certifique-se de que o Transync AI consegue capturar o \u00e1udio da sua reuni\u00e3o corretamente. Se ainda n\u00e3o o configurou, siga este guia: <a href=\"https:\/\/www.transyncai.com\/pt\/docs\/how-to-share-computer-audio\/\">Como compartilhar \u00e1udio do computador<\/a><\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">1. Ative a reprodu\u00e7\u00e3o de voz<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">No painel de idioma de destino, habilite <strong>Reprodu\u00e7\u00e3o de voz<\/strong>.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Por exemplo:<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Se voc\u00ea deseja sa\u00edda de \u00e1udio em japon\u00eas, ative-a em <strong>en \u2192 ja<\/strong><\/li>\r\n\r\n\r\n\r\n<li>Em seguida, selecione a voz que deseja usar.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">2. Selecione uma voz<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Sob <strong>Selecione Voz<\/strong>, Escolha o estilo de voz que melhor se adapte ao seu caso de uso.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Voc\u00ea pode pr\u00e9-visualizar cada voz dispon\u00edvel antes de aplic\u00e1-la. Use o controle de pr\u00e9-visualiza\u00e7\u00e3o ao lado de um estilo de voz para ouvir primeiro e, em seguida, escolha o tom que melhor se adapta \u00e0 sua reuni\u00e3o, aula, demonstra\u00e7\u00e3o ou conversa do dia a dia.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2330\" class=\"wp-image-4440\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/voice-playback-style-preview-scaled.png\" alt=\"Pr\u00e9-visualiza\u00e7\u00e3o do estilo de reprodu\u00e7\u00e3o de voz com IA da Transync\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/voice-playback-style-preview-scaled.png 2560w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/voice-playback-style-preview-300x273.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/voice-playback-style-preview-1024x932.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/voice-playback-style-preview-768x699.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/voice-playback-style-preview-1536x1398.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/voice-playback-style-preview-2048x1864.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/voice-playback-style-preview-13x12.png 13w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">&nbsp;<\/p>\r\n<p>Voc\u00ea pode usar vozes diferentes dependendo de:<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>tom de reuni\u00e3o<\/li>\r\n\r\n\r\n\r\n<li>prefer\u00eancia do p\u00fablico<\/li>\r\n\r\n\r\n\r\n<li>clareza e conforto auditivo<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">3. Ajustar o volume<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Use o controle de volume para ajustar o volume da reprodu\u00e7\u00e3o.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Em muitos casos, outros participantes podem ouvir a reprodu\u00e7\u00e3o diretamente pelos alto-falantes do seu computador. A documenta\u00e7\u00e3o atual observa que, geralmente, o uso dos alto-falantes do computador \u00e9 suficiente para que os outros participantes da reuni\u00e3o ou\u00e7am a transmiss\u00e3o do \u00e1udio.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" class=\"wp-image-3304\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-setting-1024x1024.png\" alt=\"Painel de configura\u00e7\u00f5es de reprodu\u00e7\u00e3o de voz com IA da Transync, mostrando como abrir a reprodu\u00e7\u00e3o de voz, ativar Iniciar Reprodu\u00e7\u00e3o, selecionar uma voz e ajustar o volume de reprodu\u00e7\u00e3o.\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-setting-1024x1024.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-setting-300x300.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-setting-150x150.png 150w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-setting-768x768.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-setting-12x12.png 12w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-setting-140x140.png 140w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-setting-100x100.png 100w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-setting-500x500.png 500w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-setting-350x350.png 350w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-setting-1000x1000.png 1000w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-setting-800x800.png 800w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-setting.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n\r\n\r\n\r\n<div class=\"wp-block-spacer\" style=\"height: 32px;\" aria-hidden=\"true\">\u00a0<\/div>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">4. Quando voc\u00ea tamb\u00e9m precisa compartilhar a reprodu\u00e7\u00e3o na reuni\u00e3o<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Se voc\u00ea estiver usando fones de ouvido ou se outras pessoas na reuni\u00e3o n\u00e3o conseguirem ouvir a reprodu\u00e7\u00e3o da sua voz, talvez seja necess\u00e1rio compartilhar o \u00e1udio. <strong>tela<\/strong> e <strong>\u00e1udio de computador<\/strong> dentro da plataforma de reuni\u00e3o. O Teams usa &quot;Incluir som do computador&quot;, o Zoom usa &quot;Compartilhar som&quot; e o Google Meet usa &quot;Apresentar agora \u2192 Uma guia&quot; com o \u00e1udio da guia ativado.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"702\" class=\"wp-image-3305\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/share-computer-audio-in-online-meeting-1024x702.png\" alt=\"Painel de compartilhamento do Microsoft Teams com a op\u00e7\u00e3o Incluir som ativada, permitindo que a reprodu\u00e7\u00e3o de voz por IA da Transync seja compartilhada com os participantes da reuni\u00e3o.\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/share-computer-audio-in-online-meeting-1024x702.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/share-computer-audio-in-online-meeting-300x206.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/share-computer-audio-in-online-meeting-768x527.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/share-computer-audio-in-online-meeting-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/share-computer-audio-in-online-meeting.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n\r\n\r\n\r\n<div class=\"wp-block-spacer\" style=\"height: 32px;\" aria-hidden=\"true\">\u00a0<\/div>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">5. Atraso na reprodu\u00e7\u00e3o<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Atraso na reprodu\u00e7\u00e3o<\/strong> Controla por quanto tempo a IA Transync espera durante uma pausa antes de come\u00e7ar a ler o resultado traduzido em voz alta.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Isso \u00e9 \u00fatil porque, em conversas reais, os falantes costumam fazer pequenas pausas entre as frases. Um pequeno atraso pode impedir que a reprodu\u00e7\u00e3o comece muito cedo e interrompa o fluxo natural.<\/p>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\">Como funciona<\/h4>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li><strong>Instant<\/strong>A reprodu\u00e7\u00e3o come\u00e7a imediatamente ap\u00f3s a tradu\u00e7\u00e3o estar conclu\u00edda.<\/li>\r\n\r\n\r\n\r\n<li><strong>1s \/ 2s \/ 3s<\/strong>A IA Transync aguarda esse per\u00edodo de sil\u00eancio antes de reiniciar a reprodu\u00e7\u00e3o.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\">Exemplo: quando o atraso de reprodu\u00e7\u00e3o est\u00e1 definido para 1 segundo<\/h4>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Se o orador fizer uma pausa, e a pausa for <strong>menos de 1 segundo<\/strong>, A reprodu\u00e7\u00e3o de voz ir\u00e1 <strong>n\u00e3o<\/strong> Comece j\u00e1.<br \/>O sistema continuar\u00e1 aguardando porque a IA Transync pressup\u00f5e que o falante est\u00e1 dando continuidade \u00e0 mesma frase.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Somente quando a pausa na fala se torna <strong>mais de 1 segundo<\/strong> A reprodu\u00e7\u00e3o ser\u00e1 iniciada.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Em termos simples:<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>pausa <strong>menores de 1 ano<\/strong> \u2192 fazer <strong>n\u00e3o<\/strong> iniciar reprodu\u00e7\u00e3o<\/li>\r\n\r\n\r\n\r\n<li>pausa <strong>mais de 1s<\/strong> \u2192 iniciar reprodu\u00e7\u00e3o<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Isso ajuda a evitar \u00e1udio fragmentado e faz com que a transmiss\u00e3o soe mais completa e natural.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"788\" class=\"wp-image-3306\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-delay-1024x788.png\" alt=\"Painel de configura\u00e7\u00f5es de reprodu\u00e7\u00e3o de voz com IA da Transync mostrando a op\u00e7\u00e3o Atraso de Reprodu\u00e7\u00e3o definida para 1 segundo.\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-delay-1024x788.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-delay-300x231.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-delay-768x591.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-delay-16x12.png 16w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/03\/voice-playback-delay.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n\r\n\r\n\r\n<div class=\"wp-block-spacer\" style=\"height: 32px;\" aria-hidden=\"true\">\u00a0<\/div>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">6. Configura\u00e7\u00f5es recomendadas<\/h3>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\">Use Instant quando:<\/h4>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Voc\u00ea deseja a reprodu\u00e7\u00e3o mais r\u00e1pida poss\u00edvel.<\/li>\r\n\r\n\r\n\r\n<li>Respostas curtas e r\u00e1pidas importam mais do que uma fraseologia natural.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\">Use 1s quando:<\/h4>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Voc\u00ea busca um equil\u00edbrio entre velocidade e reprodu\u00e7\u00e3o mais fluida.<\/li>\r\n\r\n\r\n\r\n<li>Os falantes tendem a fazer breves pausas no meio da frase.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h4 class=\"wp-block-heading\">Use 2s\u20133s quando:<\/h4>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Os falantes falam em blocos mais longos.<\/li>\r\n\r\n\r\n\r\n<li>Voc\u00ea deseja que a reprodu\u00e7\u00e3o aguarde grupos de frases mais completos.<\/li>\r\n\r\n\r\n\r\n<li>Voc\u00ea deseja reduzir as interrup\u00e7\u00f5es excessivamente frequentes.<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">7. Evite o eco<\/h3>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Se ambos os lados estiverem usando a reprodu\u00e7\u00e3o ao mesmo tempo, pode ocorrer eco ou repeti\u00e7\u00e3o de som. Recomendamos ativar a transmiss\u00e3o de voz apenas em um dos lados caso ocorra eco.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\">Pontas<\/h3>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>Use alto-falantes se quiser que todos ao redor ou\u00e7am o \u00e1udio traduzido.<\/li>\r\n\r\n\r\n\r\n<li>Use o compartilhamento de tela e \u00e1udio se as pessoas na reuni\u00e3o online precisarem ouvir a reprodu\u00e7\u00e3o.<\/li>\r\n\r\n\r\n\r\n<li>Comece com <strong>1s<\/strong> atraso de reprodu\u00e7\u00e3o para a maioria dos cen\u00e1rios de reuni\u00e3o<\/li>\r\n\r\n\r\n\r\n<li>Se a reprodu\u00e7\u00e3o parecer muito inst\u00e1vel, aumente o atraso.<\/li>\r\n\r\n\r\n\r\n<li>Se a reprodu\u00e7\u00e3o estiver muito lenta, mude para <strong>Instant<\/strong> ou reduzir o atraso<\/li>\r\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A Reprodu\u00e7\u00e3o de Voz permite que a IA da Transync leia o texto traduzido em voz alta no idioma de destino selecionado. Isso \u00e9 \u00fatil quando voc\u00ea quer que outras pessoas ou\u00e7am a tradu\u00e7\u00e3o, e n\u00e3o apenas leiam as legendas.<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"doc_category":[183],"doc_tag":[],"class_list":["post-3303","docs","type-docs","status-publish","doc_category-user-guide"],"year_month":"2026-07","word_count":626,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"Rixin Wang","author_nicename":"rixin-wang","author_url":"https:\/\/www.transyncai.com\/pt\/author\/rixin-wang\/"},"doc_category_info":[{"term_name":"User Guide","term_url":"https:\/\/www.transyncai.com\/pt\/docs-category\/user-guide\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/www.transyncai.com\/pt\/wp-json\/wp\/v2\/docs\/3303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.transyncai.com\/pt\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.transyncai.com\/pt\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.transyncai.com\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.transyncai.com\/pt\/wp-json\/wp\/v2\/comments?post=3303"}],"version-history":[{"count":6,"href":"https:\/\/www.transyncai.com\/pt\/wp-json\/wp\/v2\/docs\/3303\/revisions"}],"predecessor-version":[{"id":4459,"href":"https:\/\/www.transyncai.com\/pt\/wp-json\/wp\/v2\/docs\/3303\/revisions\/4459"}],"wp:attachment":[{"href":"https:\/\/www.transyncai.com\/pt\/wp-json\/wp\/v2\/media?parent=3303"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/www.transyncai.com\/pt\/wp-json\/wp\/v2\/doc_category?post=3303"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.transyncai.com\/pt\/wp-json\/wp\/v2\/doc_tag?post=3303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}