{"id":4027,"date":"2026-05-11T13:23:44","date_gmt":"2026-05-11T05:23:44","guid":{"rendered":"https:\/\/www.transyncai.com\/?post_type=docs&#038;p=4027"},"modified":"2026-05-12T23:29:34","modified_gmt":"2026-05-12T15:29:34","password":"","slug":"how-to-set-up-virtual-microphone-on-windows","status":"publish","type":"docs","link":"https:\/\/www.transyncai.com\/it\/docs\/how-to-set-up-virtual-microphone-on-windows\/","title":{"rendered":"Come configurare un microfono virtuale su Windows"},"content":{"rendered":"<h3 class=\"wp-block-heading\"><strong>Come configurare un microfono virtuale su Windows<\/strong><\/h3>\n\n\n\n<p>Il microfono virtuale Transync AI consente agli altri partecipanti alla riunione di ascoltare la tua voce tradotta direttamente tramite l&#039;ingresso del microfono. Invece di riprodurre l&#039;audio tradotto dal tuo altoparlante, Transync AI invia la voce tradotta a un dispositivo audio virtuale che pu\u00f2 essere selezionato in Zoom, Microsoft Teams, Google Meet o altre app per riunioni.<\/p>\n\n\n\n<p>Utilizza questa funzione quando desideri parlare in modo naturale nella tua lingua mentre gli altri partecipanti alla riunione ascoltano la traduzione. Ad esempio, puoi parlare in inglese, attivare la riproduzione vocale dall&#039;inglese allo spagnolo e scegliere il microfono virtuale come ingresso microfonico nel software della riunione, in modo che gli altri ascoltino direttamente la riproduzione in spagnolo.<\/p>\n\n\n\n<p>Questa guida \u00e8 per <strong>Windows<\/strong>. Se stai utilizzando macOS, fai riferimento a <a href=\"https:\/\/www.transyncai.com\/it\/docs\/virtual-microphone\/\">Come utilizzare il microfono virtuale su macOS<\/a> Invece.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dispositivi e piattaforme di riunione supportati<\/strong><\/h3>\n\n\n\n<p>Su Windows, il microfono virtuale Transync AI pu\u00f2 essere utilizzato sia con l&#039;app Transync AI per Windows che con la versione Web di Transync AI.<\/p>\n\n\n\n<p>Funziona con le piattaforme per riunioni online che consentono di scegliere l&#039;ingresso del microfono, tra cui Zoom, Microsoft Teams, Google Meet e altre applicazioni per riunioni basate su browser o desktop.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"286\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-1024x286.jpg\" alt=\"Piattaforme per riunioni supportate per il microfono virtuale Transync AI su Windows\" class=\"wp-image-3852\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-1024x286.jpg 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-300x84.jpg 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-768x215.jpg 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-1536x429.jpg 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-2048x572.jpg 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-18x5.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Prima di iniziare<\/strong><\/h3>\n\n\n\n<p>Se non hai familiarit\u00e0 con Transync AI, queste guide potrebbero esserti utili:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.transyncai.com\/it\/docs\/quickstart\/\">Avvio rapido<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.transyncai.com\/it\/docs\/how-to-start-real-time-translation\/\">Come avviare la traduzione in tempo reale<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.transyncai.com\/it\/docs\/how-to-use-voice-playback-in-transync-ai\/\">Come utilizzare la riproduzione vocale in Transync AI<\/a><\/li>\n<\/ul>\n\n\n\n<p>\u00c8 inoltre necessario assicurarsi che Transync AI sia in grado di acquisire il segnale dal microfono reale e che la riproduzione vocale funzioni nella direzione della lingua di destinazione che si desidera trasmettere.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Importante: attiva solo la direzione di riproduzione che desideri far ascoltare agli altri.<\/strong><\/h3>\n\n\n\n<p>Per il microfono virtuale, consigliamo di abilitare la riproduzione vocale solo per la direzione linguistica che si desidera trasmettere.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Se parli inglese e vuoi che gli altri sentano lo spagnolo, attiva la riproduzione vocale solo per la traduzione dall&#039;inglese allo spagnolo.<\/li>\n\n\n\n<li>Non attivare anche la riproduzione da spagnolo a inglese, a meno che tu non voglia intenzionalmente che anche quell&#039;audio venga inviato alla riunione.<\/li>\n<\/ul>\n\n\n\n<p>Se entrambe le direzioni sono abilitate, il discorso dell&#039;altro partecipante potrebbe essere tradotto e riprodotto tramite il tuo microfono virtuale. In questo modo, l&#039;altra persona potr\u00e0 ascoltare il proprio discorso tradotto dal tuo punto di vista.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1. Scarica e installa VB-Audio VB-CABLE<\/strong><\/h3>\n\n\n\n<p>Scarica prima un microfono virtuale di terze parti o un plugin audio virtuale. Consigliamo <a href=\"https:\/\/vb-audio.com\/Cable\/\" target=\"_blank\" rel=\"noreferrer noopener\">VB-Audio Virtual Cable<\/a>, che crea i dispositivi audio virtuali necessari per collegare la riproduzione vocale tradotta di Transync AI al software per le riunioni.<\/p>\n\n\n\n<p>Scarica il pacchetto, estrai il file ZIP in una cartella locale, quindi esegui il file di installazione a 64 bit se stai utilizzando Windows a 64 bit. Nella finestra di installazione, fai clic su <strong>Install Driver<\/strong>. Dopo l&#039;installazione, riavvia il computer se il programma di installazione o Windows te lo richiedono.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1107\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-scaled.png\" alt=\"Scarica, estrai e installa VB-Audio Virtual Cable per Transync AI Virtual Microphone su Windows.\" class=\"wp-image-4034\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-scaled.png 2560w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-300x130.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-1024x443.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-768x332.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-1536x664.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-2048x886.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-18x8.png 18w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2. Selezionare l&#039;CABLE Input come uscita per gli altoparlanti Transync AI.<\/strong><\/h3>\n\n\n\n<p>Apri il <strong>Microfono<\/strong> menu in Transync AI. Sotto il <strong>Oratore<\/strong> sezione, selezionare <strong>CABLE Input (VB-Audio Virtual Cable)<\/strong>.<\/p>\n\n\n\n<p>Questo passaggio invia la riproduzione della voce tradotta da Transync AI al cavo audio virtuale anzich\u00e9 riprodurla direttamente attraverso gli altoparlanti fisici.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1799\" height=\"1199\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker.png\" alt=\"Nel menu delle sorgenti audio di Transync AI su Windows, seleziona &quot;CABLE Input&quot; come uscita per gli altoparlanti.\" class=\"wp-image-4036\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker.png 1799w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker-300x200.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker-1024x682.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker-768x512.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker-1536x1024.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker-900x600.png 900w\" sizes=\"auto, (max-width: 1799px) 100vw, 1799px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. Attiva la riproduzione vocale per la lingua che desideri trasmettere.<\/strong><\/h3>\n\n\n\n<p>Apri le impostazioni di riproduzione vocale nella direzione in cui gli altri partecipanti devono ascoltare. Ad esempio, se parli inglese e vuoi che tutti i partecipanti alla riunione sentano il cinese, apri la sezione Inglese \u2192 Cinese e attiva la riproduzione vocale.<\/p>\n\n\n\n<p>\u00c8 possibile selezionare una voce e regolare il ritardo di riproduzione, se necessario. Se si desidera che la voce tradotta sia pi\u00f9 simile alla propria, consultare <a href=\"https:\/\/www.transyncai.com\/it\/docs\/voice-clone\/\">Come utilizzare Voice Clone<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1799\" height=\"1199\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback.png\" alt=\"Attiva la riproduzione vocale per la lingua di destinazione in Transync AI su Windows.\" class=\"wp-image-4037\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback.png 1799w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback-300x200.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback-1024x682.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback-768x512.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback-1536x1024.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback-900x600.png 900w\" sizes=\"auto, (max-width: 1799px) 100vw, 1799px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4. Avviare l&#039;attivit\u00e0 di traduzione<\/strong><\/h3>\n\n\n\n<p>Fai clic sul pulsante Avvia in Transync AI per iniziare l&#039;attivit\u00e0 di traduzione. Mantieni Transync AI in esecuzione durante la riunione in modo che la riproduzione della voce tradotta possa continuare a fluire nel dispositivo audio virtuale.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5. Seleziona Uscita CAVO come microfono per la riunione.<\/strong><\/h3>\n\n\n\n<p>Apri il software per le riunioni, ad esempio Zoom, Microsoft Teams o Google Meet. Nelle impostazioni audio della riunione, seleziona <strong>CABLE Output (VB-Audio Virtual Cable)<\/strong> come ingresso del microfono.<\/p>\n\n\n\n<p>Dopodich\u00e9, gli altri partecipanti ascolteranno la traduzione audio prodotta da Transync AI tramite il microfono della riunione.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1799\" height=\"1970\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone.png\" alt=\"Nel software per riunioni su Windows, selezionare &quot;Uscita CAVO&quot; come ingresso microfono.\" class=\"wp-image-4038\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone.png 1799w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone-274x300.png 274w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone-935x1024.png 935w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone-768x841.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone-1403x1536.png 1403w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone-11x12.png 11w\" sizes=\"auto, (max-width: 1799px) 100vw, 1799px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Suggerimenti<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Installa il microfono virtuale di terze parti o il plugin audio virtuale prima dell&#039;inizio della riunione, soprattutto se \u00e8 la prima volta che lo utilizzi.<\/li>\n\n\n\n<li>In Transync AI, selezionare CABLE Input come uscita per gli altoparlanti.<\/li>\n\n\n\n<li>Nell&#039;app per le riunioni, seleziona Uscita CAVO come ingresso del microfono.<\/li>\n\n\n\n<li>Abilita solo la direzione di riproduzione vocale che desideri trasmettere.<\/li>\n\n\n\n<li>Se gli altri partecipanti non riescono a sentire la voce tradotta, verificare sia l&#039;uscita audio dell&#039;altoparlante Transync AI sia l&#039;ingresso del microfono della riunione.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Domande frequenti<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Qual \u00e8 la differenza tra la configurazione del microfono virtuale su Windows e su macOS?<\/strong><\/h4>\n\n\n\n<p>Su macOS, il microfono virtuale pu\u00f2 essere attivato direttamente in Transync AI. Su Windows, \u00e8 necessario prima installare un microfono virtuale di terze parti o un plugin audio virtuale, quindi collegare l&#039;uscita altoparlante di Transync AI all&#039;ingresso microfono dell&#039;app per le riunioni. Per le istruzioni su macOS, vedere <a href=\"https:\/\/www.transyncai.com\/it\/docs\/virtual-microphone\/\">Come utilizzare il microfono virtuale su macOS<\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Gli altri partecipanti sentono la mia voce originale?<\/strong><\/h4>\n\n\n\n<p>Se la configurazione \u00e8 corretta, gli altri partecipanti ascoltano la riproduzione tradotta tramite l&#039;ingresso del microfono virtuale, e non l&#039;audio originale del microfono.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Devo comunque selezionare il mio microfono reale in Transync AI?<\/strong><\/h4>\n\n\n\n<p>S\u00ec. Transync AI ha comunque bisogno del tuo microfono reale per catturare la tua voce. Il software per le riunioni dovrebbe utilizzare l&#039;CABLE Output come ingresso del microfono, mentre Transync AI dovrebbe utilizzare il tuo microfono reale come sorgente audio.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Devo attivare la riproduzione vocale per entrambe le direzioni linguistiche?<\/strong><\/h4>\n\n\n\n<p>Di solito no. Per il microfono virtuale, consigliamo di attivare solo la direzione da cui si desidera che gli altri partecipanti sentano.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Posso utilizzare Voice Clone con Virtual Microphone?<\/strong><\/h4>\n\n\n\n<p>S\u00ec. Se la lingua di destinazione supporta Voice Clone, puoi utilizzarlo insieme a Virtual Microphone. Vedi <a href=\"https:\/\/www.transyncai.com\/it\/docs\/voice-clone\/\">Come utilizzare Voice Clone<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Learn how to set up Transync AI Virtual Microphone on Windows so meeting participants can hear translated voice through your meeting microphone input.<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"doc_category":[183],"doc_tag":[],"class_list":{"0":"post-4027","1":"docs","2":"type-docs","3":"status-publish","5":"doc_category-user-guide"},"year_month":"2026-05","word_count":917,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"Rixin Wang","author_nicename":"rixin-wang","author_url":"https:\/\/www.transyncai.com\/it\/author\/rixin-wang\/"},"doc_category_info":[{"term_name":"User Guide","term_url":"https:\/\/www.transyncai.com\/it\/docs-category\/user-guide\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/www.transyncai.com\/it\/wp-json\/wp\/v2\/docs\/4027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.transyncai.com\/it\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.transyncai.com\/it\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.transyncai.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.transyncai.com\/it\/wp-json\/wp\/v2\/comments?post=4027"}],"version-history":[{"count":10,"href":"https:\/\/www.transyncai.com\/it\/wp-json\/wp\/v2\/docs\/4027\/revisions"}],"predecessor-version":[{"id":4103,"href":"https:\/\/www.transyncai.com\/it\/wp-json\/wp\/v2\/docs\/4027\/revisions\/4103"}],"wp:attachment":[{"href":"https:\/\/www.transyncai.com\/it\/wp-json\/wp\/v2\/media?parent=4027"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/www.transyncai.com\/it\/wp-json\/wp\/v2\/doc_category?post=4027"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.transyncai.com\/it\/wp-json\/wp\/v2\/doc_tag?post=4027"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}