{"id":4027,"date":"2026-05-11T13:23:44","date_gmt":"2026-05-11T05:23:44","guid":{"rendered":"https:\/\/www.transyncai.com\/?post_type=docs&#038;p=4027"},"modified":"2026-05-12T23:29:34","modified_gmt":"2026-05-12T15:29:34","password":"","slug":"how-to-set-up-virtual-microphone-on-windows","status":"publish","type":"docs","link":"https:\/\/www.transyncai.com\/es\/docs\/how-to-set-up-virtual-microphone-on-windows\/","title":{"rendered":"C\u00f3mo configurar un micr\u00f3fono virtual en Windows"},"content":{"rendered":"<h3 class=\"wp-block-heading\"><strong>C\u00f3mo configurar un micr\u00f3fono virtual en Windows<\/strong><\/h3>\n\n\n\n<p>El micr\u00f3fono virtual Transync AI permite que los dem\u00e1s participantes de tu reuni\u00f3n escuchen tu voz traducida directamente a trav\u00e9s de la entrada de micr\u00f3fono. En lugar de reproducir el audio traducido desde tu altavoz, Transync AI env\u00eda la voz traducida a un dispositivo de audio virtual que puedes seleccionar en Zoom, Microsoft Teams, Google Meet u otras aplicaciones de reuniones.<\/p>\n\n\n\n<p>Utilice esta funci\u00f3n cuando desee hablar con naturalidad en su propio idioma mientras los dem\u00e1s participantes de la reuni\u00f3n escuchan la traducci\u00f3n. Por ejemplo, puede hablar en ingl\u00e9s, activar la reproducci\u00f3n de audio en espa\u00f1ol y seleccionar el micr\u00f3fono virtual como entrada de micr\u00f3fono en el software de la reuni\u00f3n para que los dem\u00e1s escuchen la reproducci\u00f3n en espa\u00f1ol directamente.<\/p>\n\n\n\n<p>Esta gu\u00eda es para <strong>Windows<\/strong>. Si utiliza macOS, consulte <a href=\"https:\/\/www.transyncai.com\/es\/docs\/virtual-microphone\/\">C\u00f3mo usar el micr\u00f3fono virtual en macOS<\/a> en cambio.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dispositivos y plataformas de reuniones compatibles<\/strong><\/h3>\n\n\n\n<p>En Windows, el micr\u00f3fono virtual Transync AI se puede utilizar tanto con la aplicaci\u00f3n Transync AI para Windows como con la versi\u00f3n Web de Transync AI.<\/p>\n\n\n\n<p>Funciona con plataformas de reuniones en l\u00ednea que permiten seleccionar una entrada de micr\u00f3fono, como Zoom, Microsoft Teams, Google Meet y otras aplicaciones de reuniones basadas en navegador o en ordenador.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"286\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-1024x286.jpg\" alt=\"Plataformas de reuniones compatibles con el micr\u00f3fono virtual Transync AI en Windows\" class=\"wp-image-3852\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-1024x286.jpg 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-300x84.jpg 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-768x215.jpg 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-1536x429.jpg 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-2048x572.jpg 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/04\/meeting-platforms-18x5.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Antes de empezar<\/strong><\/h3>\n\n\n\n<p>Si eres nuevo en Transync AI, estas gu\u00edas pueden ayudarte:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.transyncai.com\/es\/docs\/quickstart\/\">Inicio r\u00e1pido<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.transyncai.com\/es\/docs\/how-to-start-real-time-translation\/\">C\u00f3mo iniciar la traducci\u00f3n en tiempo real<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.transyncai.com\/es\/docs\/how-to-use-voice-playback-in-transync-ai\/\">C\u00f3mo usar la reproducci\u00f3n de voz en Transync AI<\/a><\/li>\n<\/ul>\n\n\n\n<p>Tambi\u00e9n debes asegurarte de que Transync AI pueda capturar tu micr\u00f3fono real y que la reproducci\u00f3n de voz funcione en el idioma de destino que deseas transmitir.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Importante: Activa solo la direcci\u00f3n de reproducci\u00f3n que deseas que escuchen los dem\u00e1s.<\/strong><\/h3>\n\n\n\n<p>Para el micr\u00f3fono virtual, recomendamos habilitar la reproducci\u00f3n de voz \u00fanicamente para el idioma que desea transmitir.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Si hablas ingl\u00e9s y quieres que los dem\u00e1s oigan espa\u00f1ol, activa la reproducci\u00f3n de voz solo para la traducci\u00f3n de ingl\u00e9s a espa\u00f1ol.<\/li>\n\n\n\n<li>No actives la reproducci\u00f3n de espa\u00f1ol a ingl\u00e9s a menos que quieras que ese audio tambi\u00e9n se env\u00ede a la reuni\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p>Si ambas direcciones est\u00e1n habilitadas, el discurso del otro participante puede traducirse y reproducirse a trav\u00e9s de tu micr\u00f3fono virtual. Esto permite que la otra persona escuche su propio discurso traducido desde tu lado.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1. Descargue e instale VB-Audio VB-CABLE<\/strong><\/h3>\n\n\n\n<p>Primero, descarga un micr\u00f3fono virtual de terceros o un plugin de audio virtual. Recomendamos <a href=\"https:\/\/vb-audio.com\/Cable\/\" target=\"_blank\" rel=\"noreferrer noopener\">VB-Audio Virtual Cable<\/a>, que crea los dispositivos de audio virtuales necesarios para conectar la reproducci\u00f3n de voz traducida de Transync AI con su software de reuniones.<\/p>\n\n\n\n<p>Descargue el paquete, extraiga el archivo ZIP a una carpeta local y luego ejecute el archivo de instalaci\u00f3n de 64 bits si est\u00e1 utilizando Windows de 64 bits. En la ventana del instalador, haga clic en <strong>Install Driver<\/strong>. Tras la instalaci\u00f3n, reinicie el ordenador si el instalador o Windows se lo solicita.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1107\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-scaled.png\" alt=\"Descargue, extraiga e instale VB-Audio Virtual Cable para el micr\u00f3fono virtual Transync AI en Windows.\" class=\"wp-image-4034\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-scaled.png 2560w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-300x130.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-1024x443.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-768x332.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-1536x664.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-2048x886.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-vbcable-download-install-steps-18x8.png 18w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2. Seleccione CABLE Input como salida de altavoz de Transync AI.<\/strong><\/h3>\n\n\n\n<p>Abrir el <strong>Micr\u00f3fono<\/strong> men\u00fa en Transync AI. Debajo del <strong>Vocero<\/strong> secci\u00f3n, seleccione <strong>CABLE Input (VB-Audio Virtual Cable)<\/strong>.<\/p>\n\n\n\n<p>Este paso env\u00eda la reproducci\u00f3n de voz traducida de Transync AI al cable de audio virtual en lugar de reproducirla directamente a trav\u00e9s de los altavoces f\u00edsicos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1799\" height=\"1199\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker.png\" alt=\"En el men\u00fa de fuentes de audio de Transync AI en Windows, seleccione CABLE Input como salida de altavoz.\" class=\"wp-image-4036\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker.png 1799w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker-300x200.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker-1024x682.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker-768x512.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker-1536x1024.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-transync-cable-input-speaker-900x600.png 900w\" sizes=\"auto, (max-width: 1799px) 100vw, 1799px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. Active la reproducci\u00f3n de voz para el idioma que desea transmitir.<\/strong><\/h3>\n\n\n\n<p>Abra la configuraci\u00f3n de reproducci\u00f3n de voz para indicar en qu\u00e9 idioma deben escuchar los dem\u00e1s participantes. Por ejemplo, si usted habla ingl\u00e9s y desea que en la reuni\u00f3n se escuche chino, abra la opci\u00f3n Ingl\u00e9s \u2192 Chino y active la reproducci\u00f3n de voz.<\/p>\n\n\n\n<p>Puedes seleccionar una voz y ajustar el retardo de reproducci\u00f3n si es necesario. Si quieres que la voz traducida suene m\u00e1s parecida a tu propia voz, consulta <a href=\"https:\/\/www.transyncai.com\/es\/docs\/voice-clone\/\">C\u00f3mo usar Voice Clone<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1799\" height=\"1199\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback.png\" alt=\"Habilita la reproducci\u00f3n de voz para la direcci\u00f3n del idioma de destino en Transync AI en Windows.\" class=\"wp-image-4037\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback.png 1799w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback-300x200.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback-1024x682.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback-768x512.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback-1536x1024.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-enable-voice-playback-900x600.png 900w\" sizes=\"auto, (max-width: 1799px) 100vw, 1799px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4. Iniciar la tarea de traducci\u00f3n<\/strong><\/h3>\n\n\n\n<p>Haz clic en el bot\u00f3n Iniciar en Transync AI para comenzar la traducci\u00f3n. Mant\u00e9n Transync AI en funcionamiento durante la reuni\u00f3n para que la reproducci\u00f3n de la voz traducida siga fluyendo hacia el dispositivo de audio virtual.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5. Seleccione CABLE Output como micr\u00f3fono para la reuni\u00f3n.<\/strong><\/h3>\n\n\n\n<p>Abra su software de reuniones, como Zoom, Microsoft Teams o Google Meet. En la configuraci\u00f3n de audio de la reuni\u00f3n, seleccione <strong>CABLE Output (VB-Audio Virtual Cable)<\/strong> como entrada de micr\u00f3fono.<\/p>\n\n\n\n<p>Despu\u00e9s de esto, los dem\u00e1s participantes escuchar\u00e1n la reproducci\u00f3n traducida de Transync AI a trav\u00e9s de la entrada de micr\u00f3fono de la reuni\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1799\" height=\"1970\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone.png\" alt=\"En el software de reuniones de Windows, seleccione CABLE Output como entrada de micr\u00f3fono.\" class=\"wp-image-4038\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone.png 1799w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone-274x300.png 274w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone-935x1024.png 935w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone-768x841.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone-1403x1536.png 1403w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2026\/05\/windows-meeting-cable-output-microphone-11x12.png 11w\" sizes=\"auto, (max-width: 1799px) 100vw, 1799px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Consejos<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Instale el micr\u00f3fono virtual de terceros o el complemento de audio virtual antes de que comience la reuni\u00f3n, especialmente si es la primera vez que lo utiliza.<\/li>\n\n\n\n<li>En Transync AI, seleccione CABLE Input como salida de altavoz.<\/li>\n\n\n\n<li>En la aplicaci\u00f3n de reuniones, seleccione CABLE Output como entrada de micr\u00f3fono.<\/li>\n\n\n\n<li>Habilite \u00fanicamente la direcci\u00f3n de reproducci\u00f3n de voz que desee transmitir.<\/li>\n\n\n\n<li>Si los dem\u00e1s participantes no pueden o\u00edr la voz traducida, compruebe tanto la salida del altavoz de Transync AI como la entrada del micr\u00f3fono de la reuni\u00f3n.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Preguntas frecuentes<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfCu\u00e1l es la diferencia entre la configuraci\u00f3n del micr\u00f3fono virtual en Windows y macOS?<\/strong><\/h4>\n\n\n\n<p>En macOS, el micr\u00f3fono virtual se puede activar directamente en Transync AI. En Windows, primero debe instalar un micr\u00f3fono virtual o un complemento de audio virtual de terceros y luego conectar la salida de altavoz de Transync AI a la entrada de micr\u00f3fono de su aplicaci\u00f3n de reuniones. Para obtener instrucciones para macOS, consulte <a href=\"https:\/\/www.transyncai.com\/es\/docs\/virtual-microphone\/\">C\u00f3mo usar el micr\u00f3fono virtual en macOS<\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfLos dem\u00e1s participantes oyen mi voz original?<\/strong><\/h4>\n\n\n\n<p>Cuando la configuraci\u00f3n es correcta, los dem\u00e1s participantes oyen la reproducci\u00f3n traducida a trav\u00e9s de la entrada del micr\u00f3fono virtual, no el audio original de tu micr\u00f3fono.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfA\u00fan necesito seleccionar mi micr\u00f3fono real en Transync AI?<\/strong><\/h4>\n\n\n\n<p>S\u00ed. Transync AI a\u00fan necesita tu micr\u00f3fono real para capturar tu voz. Tu software de reuniones debe usar la CABLE Output como entrada de micr\u00f3fono, mientras que Transync AI debe usar tu micr\u00f3fono real como fuente de audio.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfDebo activar la reproducci\u00f3n de voz para ambos idiomas?<\/strong><\/h4>\n\n\n\n<p>Normalmente no. Para el micr\u00f3fono virtual, recomendamos activarlo \u00fanicamente en la direcci\u00f3n que desea que escuchen los dem\u00e1s participantes.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00bfPuedo usar Voice Clone con un micr\u00f3fono virtual?<\/strong><\/h4>\n\n\n\n<p>S\u00ed. Si el idioma de destino admite la funci\u00f3n Clonaci\u00f3n de voz, puede usarla junto con el Micr\u00f3fono virtual. Ver <a href=\"https:\/\/www.transyncai.com\/es\/docs\/voice-clone\/\">C\u00f3mo usar Voice Clone<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Learn how to set up Transync AI Virtual Microphone on Windows so meeting participants can hear translated voice through your meeting microphone input.<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"doc_category":[183],"doc_tag":[],"class_list":{"0":"post-4027","1":"docs","2":"type-docs","3":"status-publish","5":"doc_category-user-guide"},"year_month":"2026-05","word_count":917,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"Rixin Wang","author_nicename":"rixin-wang","author_url":"https:\/\/www.transyncai.com\/es\/author\/rixin-wang\/"},"doc_category_info":[{"term_name":"User Guide","term_url":"https:\/\/www.transyncai.com\/es\/docs-category\/user-guide\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/docs\/4027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/comments?post=4027"}],"version-history":[{"count":10,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/docs\/4027\/revisions"}],"predecessor-version":[{"id":4103,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/docs\/4027\/revisions\/4103"}],"wp:attachment":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/media?parent=4027"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/doc_category?post=4027"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/doc_tag?post=4027"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}