{"id":3301,"date":"2026-03-28T20:36:03","date_gmt":"2026-03-28T12:36:03","guid":{"rendered":"https:\/\/www.transyncai.com\/?post_type=docs&#038;p=3301"},"modified":"2026-04-22T17:22:26","modified_gmt":"2026-04-22T09:22:26","password":"","slug":"how-to-share-computer-audio","status":"publish","type":"docs","link":"https:\/\/www.transyncai.com\/es\/docs\/how-to-share-computer-audio\/","title":{"rendered":"C\u00f3mo compartir el audio de la computadora"},"content":{"rendered":"<h3 class=\"wp-block-heading\">C\u00f3mo compartir el audio de la computadora<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para garantizar que Transync AI pueda traducir a todos los participantes de su reuni\u00f3n, debe compartir el audio del sistema de su computadora. Esto permite que Transync AI capture voces no solo de su micr\u00f3fono, sino tambi\u00e9n de Zoom, Teams o Google Meet. Puede visitar nuestra p\u00e1gina <a href=\"https:\/\/www.transyncai.com\/es\/\" data-type=\"page\" data-id=\"620\">sitio web oficial<\/a> Para saber m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Habilite \u201cAudio de computadora\u201d en Transync AI<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de comenzar la traducci\u00f3n, abra la aplicaci\u00f3n Transync AI y verifique \u201c<strong>Audio de computadora.<\/strong>\u201d<br>Esto garantiza que el sonido de la reuni\u00f3n se capture directamente desde su dispositivo para su traducci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Para la aplicaci\u00f3n de escritorio (macOS, Windows)<\/h4>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-16-1024x683.png\" alt=\"Compartir audio de computadora\" class=\"wp-image-1940\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-16-1024x683.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-16-300x200.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-16-768x512.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-16-1536x1024.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-16-2048x1365.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-16-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-16-900x600.png 900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Para la aplicaci\u00f3n web<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La versi\u00f3n Web solo permite compartir el sonido desde las pesta\u00f1as del navegador. Si necesita capturar audio de videos o software de conferencias, aseg\u00farese de que ambos programas tambi\u00e9n utilicen la versi\u00f3n Web. Haga clic en la pesta\u00f1a correspondiente y seleccione &quot;Compartir el sonido de la computadora simult\u00e1neamente&quot;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"625\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-17-1024x625.png\" alt=\"\" class=\"wp-image-1941\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-17-1024x625.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-17-300x183.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-17-768x469.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-17-1536x938.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-17-2048x1250.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-17-18x12.png 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Para aplicaciones m\u00f3viles<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Por el momento, la funci\u00f3n de compartir audio del sistema m\u00f3vil no es totalmente compatible. En algunos tel\u00e9fonos, el modo de ventana flotante puede ayudar a capturar el audio de forma m\u00e1s directa.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><br><strong>2. <\/strong>Confirme sus dispositivos de entrada y salida.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Aseg\u00farese de que su computadora <strong>aporte<\/strong> y <strong>producci\u00f3n<\/strong> Los dispositivos est\u00e1n configurados correctamente:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Entrada = el micr\u00f3fono que est\u00e1s usando<\/li>\n\n\n\n<li>Salida = el altavoz o los auriculares que est\u00e1s utilizando<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n es importante que el micr\u00f3fono seleccionado en Transync AI coincida con la configuraci\u00f3n de audio actual de su ordenador.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">3. Iniciar traducci\u00f3n<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Puedes comprobar si el micr\u00f3fono funciona en Transync AI. Generalmente, si Transync AI puede recibir sonido del micr\u00f3fono, ver\u00e1s un cuadrado azul fluctuando debajo del bot\u00f3n de selecci\u00f3n del micr\u00f3fono.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"614\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-20-1024x614.png\" alt=\"\" class=\"wp-image-1946\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-20-1024x614.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-20-300x180.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-20-768x461.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-20-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-20.png 1480w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Puedes comenzar a traducir despu\u00e9s de que se haya compartido el audio de la computadora y se haya confirmado el par de idiomas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPrefieres que el audio traducido se reproduzca en voz alta en lugar de solo mostrar los subt\u00edtulos? Aprende c\u00f3mo habilitar la reproducci\u00f3n de voz, elegir una voz y ajustar el retardo de reproducci\u00f3n en nuestra gu\u00eda: <a href=\"https:\/\/www.transyncai.com\/es\/docs\/how-to-use-voice-playback-in-transync-ai\/\">C\u00f3mo usar la reproducci\u00f3n de voz en Transync AI<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Soluci\u00f3n de problemas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Si no puede acceder al micr\u00f3fono ni al audio de la computadora, podemos confirmar la configuraci\u00f3n de audio paso a paso. Siga los pasos a continuaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Para el cliente de Windows<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Seleccione el bot\u00f3n de sonido en la esquina inferior derecha de la barra de tareas de la computadora para verificar la configuraci\u00f3n de sonido. o (win+ctrl+v)<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"797\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/bca7bffae5e4373b81ef35701192ffb7-1024x797.jpg\" alt=\"\" class=\"wp-image-1947\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/bca7bffae5e4373b81ef35701192ffb7-1024x797.jpg 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/bca7bffae5e4373b81ef35701192ffb7-300x234.jpg 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/bca7bffae5e4373b81ef35701192ffb7-768x598.jpg 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/bca7bffae5e4373b81ef35701192ffb7-15x12.jpg 15w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/bca7bffae5e4373b81ef35701192ffb7.jpg 1301w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Haga clic para <strong>M\u00e1s configuraciones de volumen.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"755\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/7ff508f140b82dcc88ae9ede3fa27f6f-1-1024x755.jpg\" alt=\"\" class=\"wp-image-1949\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/7ff508f140b82dcc88ae9ede3fa27f6f-1-1024x755.jpg 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/7ff508f140b82dcc88ae9ede3fa27f6f-1-300x221.jpg 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/7ff508f140b82dcc88ae9ede3fa27f6f-1-768x567.jpg 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/7ff508f140b82dcc88ae9ede3fa27f6f-1-16x12.jpg 16w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/7ff508f140b82dcc88ae9ede3fa27f6f-1.jpg 1510w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Aseg\u00farese de que el dispositivo seleccionado en el <strong>producci\u00f3n<\/strong> es el que est\u00e1s usando actualmente, como altavoces o auriculares. Aseg\u00farate de que el control deslizante de Volumen fluct\u00fae cuando haya sonido.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"795\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/5a7d44501bfaeee58b5ef07d779763e4-1024x795.jpg\" alt=\"\" class=\"wp-image-1950\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/5a7d44501bfaeee58b5ef07d779763e4-1024x795.jpg 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/5a7d44501bfaeee58b5ef07d779763e4-300x233.jpg 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/5a7d44501bfaeee58b5ef07d779763e4-768x596.jpg 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/5a7d44501bfaeee58b5ef07d779763e4-1536x1192.jpg 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/5a7d44501bfaeee58b5ef07d779763e4-15x12.jpg 15w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/5a7d44501bfaeee58b5ef07d779763e4.jpg 1649w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Aseg\u00farese de que el dispositivo seleccionado en la entrada sea el que est\u00e1 utilizando actualmente, como un altavoz o auriculares. Aseg\u00farese de que el control deslizante de Volumen fluct\u00fae cuando haya sonido.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"522\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/6cc62a840ca0b6dc231aa135f457c885-1024x522.jpg\" alt=\"\" class=\"wp-image-1951\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/6cc62a840ca0b6dc231aa135f457c885-1024x522.jpg 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/6cc62a840ca0b6dc231aa135f457c885-300x153.jpg 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/6cc62a840ca0b6dc231aa135f457c885-768x391.jpg 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/6cc62a840ca0b6dc231aa135f457c885-1536x783.jpg 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/6cc62a840ca0b6dc231aa135f457c885-2048x1044.jpg 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/6cc62a840ca0b6dc231aa135f457c885-18x9.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Importante: aseg\u00farese de que el micr\u00f3fono en Transycn AI coincida con la configuraci\u00f3n de entrada en la configuraci\u00f3n de audio de su computadora.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"609\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-21-1024x609.png\" alt=\"\" class=\"wp-image-1953\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-21-1024x609.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-21-300x179.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-21-768x457.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-21-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-21.png 1452w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Para MacOS<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Abra la configuraci\u00f3n de la computadora y seleccione Sonido. Compruebe que la Salida y la Entrada coincidan con sus expectativas y aseg\u00farese de que el control deslizante de volumen fluct\u00fae al hablar.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"930\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-22-1024x930.png\" alt=\"\" class=\"wp-image-1954\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-22-1024x930.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-22-300x272.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-22-768x697.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-22-13x12.png 13w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-22.png 1388w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Si usa auriculares, verifique si la entrada y la salida coinciden con los dispositivos esperados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-23-1024x640.png\" alt=\"\" class=\"wp-image-1955\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-23-1024x640.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-23-300x188.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-23-768x480.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-23-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-23.png 1404w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Aseg\u00farate de que las opciones de entrada y salida de la configuraci\u00f3n de sonido de tu ordenador coincidan con las seleccionadas en Transync AI. Si no ves tus auriculares u otros dispositivos aqu\u00ed, cierra y reinicia Transync AI.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"621\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-24-1024x621.png\" alt=\"\" class=\"wp-image-1956\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-24-1024x621.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-24-300x182.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-24-768x466.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-24-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-24.png 1418w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Consejos<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Encender <strong>Audio de computadora<\/strong> antes de unirse o comenzar la reuni\u00f3n<\/li>\n\n\n\n<li>Si no se capta ning\u00fan sonido, compruebe detenidamente el micr\u00f3fono seleccionado.<\/li>\n\n\n\n<li>Si est\u00e1s usando la aplicaci\u00f3n web, recuerda que solo captura el audio de las pesta\u00f1as del navegador, no el audio de las aplicaciones de escritorio.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Puedes descargarlo ahora y probarlo. <a href=\"https:\/\/www.transyncai.com\/es\/download\/\">https:\/\/www.transyncai.com\/download\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Aprende a compartir el audio de tu computadora para que Transync AI pueda capturar todas las voces durante las reuniones de Zoom, Teams o Google Meet. Esta gu\u00eda explica c\u00f3mo activar el sonido del sistema y garantizar una traducci\u00f3n fluida en tiempo real.<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"doc_category":[183],"doc_tag":[],"class_list":["post-3301","docs","type-docs","status-publish","doc_category-user-guide"],"year_month":"2026-07","word_count":583,"total_views":0,"reactions":{"happy":0,"normal":0,"sad":0},"author_info":{"name":"Rixin Wang","author_nicename":"rixin-wang","author_url":"https:\/\/www.transyncai.com\/es\/author\/rixin-wang\/"},"doc_category_info":[{"term_name":"User Guide","term_url":"https:\/\/www.transyncai.com\/es\/docs-category\/user-guide\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/docs\/3301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/comments?post=3301"}],"version-history":[{"count":5,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/docs\/3301\/revisions"}],"predecessor-version":[{"id":3785,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/docs\/3301\/revisions\/3785"}],"wp:attachment":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/media?parent=3301"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/doc_category?post=3301"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/doc_tag?post=3301"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}