{"id":1924,"date":"2025-10-15T13:47:42","date_gmt":"2025-10-15T05:47:42","guid":{"rendered":"https:\/\/www.transyncai.com\/?post_type=docs&#038;p=1924"},"modified":"2026-06-05T18:05:26","modified_gmt":"2026-06-05T10:05:26","password":"","slug":"register-transync-ai","status":"publish","type":"docs","link":"https:\/\/www.transyncai.com\/es\/docs\/register-transync-ai\/","title":{"rendered":"C\u00f3mo registrar Transync AI"},"content":{"rendered":"<h3 class=\"wp-block-heading\"><strong>C\u00f3mo registrar Transync AI<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Empezando con <strong>Transync AI<\/strong> Es r\u00e1pido y sencillo. Sigue estos pasos para crear tu cuenta y empezar a usar la traducci\u00f3n en tiempo real en reuniones y eventos. Puedes visitar nuestra p\u00e1gina web. <a href=\"https:\/\/www.transyncai.com\/es\/\" data-type=\"page\" data-id=\"620\">sitio web oficial<\/a> Para saber m\u00e1s.<\/p>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>1. Descarga Transync AI<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Visita <a href=\"https:\/\/www.transyncai.com\/es\/download\/\">https:\/\/www.transyncai.com\/download\/<\/a> para descargar la \u00faltima versi\u00f3n de Transync AI para Windows, macOS, iOS, Android o simplemente iniciar la aplicaci\u00f3n web.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"619\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-7-1024x619.png\" alt=\"\" class=\"wp-image-1927\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-7-1024x619.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-7-300x181.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-7-768x464.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-7-1536x928.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-7-2048x1237.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-7-18x12.png 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>2. Abra la aplicaci\u00f3n y seleccione \u201cRegistrarse\/Iniciar sesi\u00f3n\u201d<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Inicie la aplicaci\u00f3n y haga clic <strong>&quot;Registro&quot;<\/strong> En la pantalla de inicio de sesi\u00f3n. Si es la primera vez que inicia sesi\u00f3n, cada cuenta recibir\u00e1 40 minutos de prueba.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-8-1024x683.png\" alt=\"\" class=\"wp-image-1928\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-8-1024x683.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-8-300x200.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-8-768x512.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-8-1536x1024.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-8-2048x1365.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-8-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-8-900x600.png 900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>3. Ingrese su informaci\u00f3n<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Introduce tu correo electr\u00f3nico o n\u00famero de tel\u00e9fono y haz clic en &quot;Enviar c\u00f3digo de verificaci\u00f3n&quot;. Aseg\u00farate de que tu correo electr\u00f3nico sea correcto. Busca el c\u00f3digo de verificaci\u00f3n en tu correo e inicia sesi\u00f3n. Tras iniciar sesi\u00f3n, la mayor\u00eda de los dispositivos conservar\u00e1n la cach\u00e9, as\u00ed que no tendr\u00e1s que volver a introducirla. Tambi\u00e9n puedes iniciar sesi\u00f3n con cuentas de redes sociales como Google o Apple.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-46-1024x683.png\" alt=\"Registrar Transync AI\" class=\"wp-image-2240\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-46-1024x683.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-46-300x200.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-46-768x512.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-46-1536x1024.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-46-2048x1365.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-46-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-46-900x600.png 900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>4. Verifique su correo electr\u00f3nico<\/strong>\/Tel\u00e9fono<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de enviar su formulario de registro, revise su bandeja de entrada para ver si recibi\u00f3 un correo electr\u00f3nico de verificaci\u00f3n de Transync AI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Haga clic en el enlace de verificaci\u00f3n para activar su cuenta.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"759\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-10-1024x759.png\" alt=\"\" class=\"wp-image-1930\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-10-1024x759.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-10-300x222.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-10-768x569.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-10-1536x1138.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-10-2048x1517.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-10-16x12.png 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">4.1 <strong>Comprueba la regi\u00f3n de tu servidor: Transyc AI (China) vs. Transyc AI (Global)<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de iniciar sesi\u00f3n, confirme qu\u00e9 versi\u00f3n de Transync AI est\u00e1 utilizando. <strong>Transync AI (China)<\/strong> o <strong>Transync AI (Global)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Transync AI (China) y Transync AI (Global) utilizan regiones de servidores independientes. Los datos comerciales de la versi\u00f3n global se alojan en Estados Unidos, mientras que los de la versi\u00f3n china se alojan en China continental. Las cuentas, el historial de traducciones, los registros de membres\u00eda, los datos de recarga y los datos comerciales no se comparten entre ambas regiones.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Las cuentas, el historial de traducci\u00f3n y los datos de membres\u00eda o recarga son <strong>no compartido<\/strong> entre las dos versiones.<\/li>\n\n\n\n<li>Los registros de membres\u00eda y el historial de traducci\u00f3n se sincronizan en la misma cuenta (misma regi\u00f3n).<\/li>\n\n\n\n<li>No hay l\u00edmite en la cantidad de dispositivos en los que puedes iniciar sesi\u00f3n ni en la cantidad de tareas de traducci\u00f3n que puedes ejecutar simult\u00e1neamente. Sin embargo, ten en cuenta que no recomendamos compartir tu cuenta con otros, ya que todo el historial de traducci\u00f3n de la misma cuenta siempre estar\u00e1 sincronizado.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Diferencias:<\/strong><\/p>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li>Si tu regi\u00f3n es <strong>fuera de China continental<\/strong>, o si utilizas frecuentemente un <strong>VPN<\/strong> o trabajar principalmente en el extranjero, elija <strong>Global<\/strong> para un rendimiento m\u00e1s r\u00e1pido y estable.<\/li>\n\n\n\n<li>Si usted se encuentra <strong>en China continental<\/strong> y hacer <strong>No utilice una VPN con regularidad<\/strong>, inicie sesi\u00f3n en el <strong>Versi\u00f3n china<\/strong>, lo que proporciona una mayor estabilidad de conexi\u00f3n dentro de China.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-47-1024x683.png\" alt=\"Iniciar sesi\u00f3n en Transync AI Global\" class=\"wp-image-2241\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-47-1024x683.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-47-300x200.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-47-768x512.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-47-1536x1024.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-47-2048x1365.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-47-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-47-900x600.png 900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-48-1024x683.png\" alt=\"Iniciar sesi\u00f3n en Transync AI cn\" class=\"wp-image-2242\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-48-1024x683.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-48-300x200.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-48-768x512.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-48-1536x1024.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-48-2048x1365.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-48-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-48-900x600.png 900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C\u00f3mo cambiar de servidor:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si necesita cambiar entre las versiones de China y Global, simplemente <strong>finalizar la sesi\u00f3n<\/strong>, luego en la ventana de inicio de sesi\u00f3n, utilice el <strong>conmutador de servidor<\/strong> opci\u00f3n en la parte superior antes de iniciar sesi\u00f3n nuevamente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-13-1024x683.png\" alt=\"\" class=\"wp-image-1933\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-13-1024x683.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-13-300x200.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-13-768x512.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-13-1536x1024.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-13-2048x1365.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-13-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-13-900x600.png 900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>5. Inicia sesi\u00f3n y comienza<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que su correo electr\u00f3nico est\u00e9 verificado y su regi\u00f3n est\u00e9 seleccionada correctamente, regrese a la aplicaci\u00f3n Transync AI e inicie sesi\u00f3n con sus nuevas credenciales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"639\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-15-1024x639.png\" alt=\"\" class=\"wp-image-1935\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-15-1024x639.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-15-300x187.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-15-768x479.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-15-1536x958.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-15-2048x1277.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-15-18x12.png 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">6. Eliminar cuenta<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Puedes encontrar el bot\u00f3n para eliminar tu cuenta en la parte inferior del centro personal.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Antes de eliminar su cuenta, es posible que deba verificar su identidad.<\/li>\n\n\n\n<li>Una vez eliminada la cuenta, todos los registros de traducci\u00f3n y la informaci\u00f3n de membres\u00eda se eliminar\u00e1n de forma permanente.<br>Si su cuenta tiene una suscripci\u00f3n activa a Stripe, Transync AI intentar\u00e1 autom\u00e1ticamente cancelar dicha suscripci\u00f3n durante la eliminaci\u00f3n de la cuenta.<br>Le prometemos que no habr\u00e1 copias de seguridad de sus datos luego de la eliminaci\u00f3n, as\u00ed que proceda con precauci\u00f3n.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-44-1024x683.png\" alt=\"Eliminar cuenta \" class=\"wp-image-2036\" srcset=\"https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-44-1024x683.png 1024w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-44-300x200.png 300w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-44-768x512.png 768w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-44-1536x1024.png 1536w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-44-2048x1365.png 2048w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-44-18x12.png 18w, https:\/\/www.transyncai.com\/wp-content\/uploads\/2025\/10\/image-44-900x600.png 900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>C\u00f3mo registrar Transync AI. Comenzar a usar Transync AI es r\u00e1pido y sencillo. Sigue estos pasos para crear tu cuenta y empezar a usar la traducci\u00f3n en tiempo real en reuniones y eventos.<\/p>","protected":false},"author":1,"featured_media":1929,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"doc_category":[183],"doc_tag":[],"class_list":["post-1924","docs","type-docs","status-publish","has-post-thumbnail","doc_category-user-guide"],"year_month":"2026-07","word_count":553,"total_views":"0","reactions":{"happy":"2","normal":"0","sad":"0"},"author_info":{"name":"TransincAI","author_nicename":"transyncai","author_url":"https:\/\/www.transyncai.com\/es\/author\/transyncai\/"},"doc_category_info":[{"term_name":"User Guide","term_url":"https:\/\/www.transyncai.com\/es\/docs-category\/user-guide\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/docs\/1924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/comments?post=1924"}],"version-history":[{"count":10,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/docs\/1924\/revisions"}],"predecessor-version":[{"id":4727,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/docs\/1924\/revisions\/4727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/media\/1929"}],"wp:attachment":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/media?parent=1924"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/doc_category?post=1924"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/doc_tag?post=1924"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}