{"id":177,"count":3,"description":"Aprende a usar Transync AI en minutos. Esta gu\u00eda te gu\u00eda por los pasos de instalaci\u00f3n, inicio de sesi\u00f3n y configuraci\u00f3n b\u00e1sica para habilitar la traducci\u00f3n en tiempo real en plataformas como Microsoft Teams, Zoom y Google Meet. Tanto si organizas una reuni\u00f3n como si te unes a ella, descubrir\u00e1s c\u00f3mo configurar la captura de audio, seleccionar idiomas y empezar a traducir al instante.","link":"https:\/\/www.transyncai.com\/es\/docs-category\/getting-started\/","name":"Empezando","slug":"getting-started","taxonomy":"doc_category","parent":0,"meta":[],"doc_category_order":"1","thumbnail":null,"handbookthumbnail":null,"subcategories_count":0,"total_docs_count":3,"last_updated_time":"junio 25, 2026","_links":{"self":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/doc_category\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/doc_category"}],"about":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/taxonomies\/doc_category"}],"wp:post_type":[{"href":"https:\/\/www.transyncai.com\/es\/wp-json\/wp\/v2\/docs?doc_category=177"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}